{"id":7819,"date":"2019-05-30T10:01:16","date_gmt":"2019-05-30T08:01:16","guid":{"rendered":"http:\/\/www.cagliarirespira.it\/2016\/?p=7819"},"modified":"2019-05-30T10:01:16","modified_gmt":"2019-05-30T08:01:16","slug":"corallo-il-nuovo-melone-de-lorto-di-eleonora-che-vale-una-medaglia-doro","status":"publish","type":"post","link":"https:\/\/cagliarirespira.it\/cr\/corallo-il-nuovo-melone-de-lorto-di-eleonora-che-vale-una-medaglia-doro\/","title":{"rendered":"Corallo: il nuovo melone de L&#8217;Orto di Eleonora che vale una medaglia d&#8217;oro"},"content":{"rendered":"<p><!--more--><!--more--><\/p>\n<p>Un melone dal gusto pregiato e dal nome ispirato a uno dei pi\u00f9 preziosi tesori dei nostri mari, il corallo. Ancora una volta, <strong>l\u2019Op Agricola Campidanese attraverso il marchio l\u2019Orto di Eleonora<\/strong>\u2013 dopo un anno dall\u2019inizio della coltivazione &#8211; presenta un prodotto unico sul mercato ortofrutticolo italiano portando alta la bandiera della qualit\u00e0 dei prodotti isolani.<\/p>\n<p><strong>Corallo\u00a0<\/strong>\u00e8 un melone a met\u00e0 tra il <em>Piel de Sapo\u00a0<\/em>(classica tipologia a pasta bianca e forma ovale) e un\u00a0<em>Charentais\u00a0<\/em>(variet\u00e0 tradizionale a pelle liscia e polpa spessa) con una variante essenziale: il gusto accattivante e la consistenza soda della sua polpa arancione. Insomma, un\u2019esplosione di gusto.<\/p>\n<p>Con un grado <em>Brix<\/em> pari a 16 e un periodo di conservazione che si aggira intorno ai 20 giorni, Corallo ha di recente conquistato un riconoscimento importante: la medaglia d\u2019oro al <em>Macfrut Innovation Award\u00a0<\/em>a Rimini come una delle migliori innovazioni ortofrutticole italiane.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7820\" src=\"http:\/\/www.cagliarirespira.it\/2016\/wp-content\/uploads\/2019\/05\/CoralloLOrto.jpg\" alt=\"CoralloL'Orto\" width=\"805\" height=\"546\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Manca davvero poco e in breve tempo troveremo questo prodotto unico e innovativo sulle\u00a0nostre tavole. Un ulteriore prodotto di qualit\u00e0 frutto del lavoro\u00a0dell\u2019Orto di Eleonora, nostro partner di fiducia che, durante <strong>l\u2019edizione 2018 della CRAI CagliariRespira<\/strong>, ha accompagnato e rigenerato gli oltre 3000 atleti partecipanti provenienti da tutta Europa.<\/p>\n<p>&nbsp;<\/p>\n<p>Ancora una volta uno dei nostri sponsor rappresenta la conferma che, in occasione della nostra mezza maratona, vi garantiremo sempre e solo il meglio dei prodotti nostrani.<\/p>\n<p>&nbsp;<\/p>\n<p>Con l\u2019augurio di collaborare ancora insieme per le future edizioni della <strong>#CRAICR<\/strong>, <strong>complimenti ancora all\u2019Orto di Eleonora!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":7821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6,21,8,3],"tags":[],"class_list":["post-7819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentazione","category-cagliari","category-comunicati-stampa","category-running_news","category-salute"],"_links":{"self":[{"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/posts\/7819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/comments?post=7819"}],"version-history":[{"count":0,"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/posts\/7819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/media?parent=7819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/categories?post=7819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cagliarirespira.it\/cr\/wp-json\/wp\/v2\/tags?post=7819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}